{"id":1677,"date":"2021-02-23T02:14:58","date_gmt":"2021-02-23T02:14:58","guid":{"rendered":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/?post_type=product&#038;p=1677"},"modified":"2021-03-11T19:03:57","modified_gmt":"2021-03-11T19:03:57","slug":"la-buena-pasta","status":"publish","type":"product","link":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/producto\/la-buena-pasta\/","title":{"rendered":"La Buena Pasta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1678,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[53],"product_tag":[],"_links":{"self":[{"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/product\/1677"}],"collection":[{"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/comments?post=1677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/media\/1678"}],"wp:attachment":[{"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/media?parent=1677"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/product_cat?post=1677"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/culinarymarket.online\/la-casa-del-gringo\/wp-json\/wp\/v2\/product_tag?post=1677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}